{"id":21880,"date":"2026-02-24T09:47:39","date_gmt":"2026-02-24T08:47:39","guid":{"rendered":"https:\/\/florianhorsefood.nl\/unkategorisiert\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/"},"modified":"2026-02-26T12:32:29","modified_gmt":"2026-02-26T11:32:29","slug":"gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten","status":"publish","type":"post","link":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/","title":{"rendered":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Schwankender Kot, Juckreiz, stumpfes Fell oder ein Pferd, das \"einfach nicht fit\" ist: Das kann verschiedene Ursachen haben, aber der Darm ist oft ein logischer Ansatzpunkt. In diesem Artikel erfahren Sie, wie Verdauung, Darmflora und Darmwand mit dem Immunsystem zusammenarbeiten, warum Beschwerden bei Stress oder saisonalen Ver\u00e4nderungen eher aufflammen und wie Sie Ihr Pferd mit einer ruhigen Futtergrundlage und einer klugen Futterauswahl von innen heraus unterst\u00fctzen k\u00f6nnen. Au\u00dferdem: welche Florian Raufuttermischung f\u00fcr welchen Pferdetyp geeignet ist und wann Sie besser den Tierarzt hinzuziehen sollten.  <\/p>\n","protected":false},"author":6,"featured_media":21886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[491,492,277,279,278,245,273],"class_list":["post-21880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-widerstand","tag-darmflora","tag-darmgesundheit","tag-pferd-mit-vermindertem-appetit","tag-reduzierte-leistung-des-pferdes","tag-schlankes-pferd","tag-widerstand","tag-widerstandspferd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood<\/title>\n<meta name=\"description\" content=\"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\/Fibre Protein) und Care Fit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\/Fibre Protein) und Care Fit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Florian Horsefood\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-24T08:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T11:32:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pieter de Gouw\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pieter de Gouw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/\"},\"author\":{\"name\":\"Pieter de Gouw\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#\\\/schema\\\/person\\\/ba5046cbcfb040cadeba68e42e52a0f5\"},\"headline\":\"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten\",\"datePublished\":\"2026-02-24T08:47:39+00:00\",\"dateModified\":\"2026-02-26T11:32:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/gezonde-darmen-paard.webp\",\"keywords\":[\"Darmflora\",\"Darmgesundheit\",\"Pferd mit vermindertem Appetit\",\"reduzierte Leistung des Pferdes\",\"Schlankes Pferd\",\"Widerstand\",\"Widerstandspferd\"],\"articleSection\":[\"Widerstand\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/\",\"url\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/\",\"name\":\"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/gezonde-darmen-paard.webp\",\"datePublished\":\"2026-02-24T08:47:39+00:00\",\"dateModified\":\"2026-02-26T11:32:29+00:00\",\"description\":\"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\\\/Fibre Protein) und Care Fit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/gezonde-darmen-paard.webp\",\"contentUrl\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/gezonde-darmen-paard.webp\",\"width\":1080,\"height\":1080,\"caption\":\"Gesunder Darm und starke Abwehrkr\u00e4fte mit Florian Horsefood.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/widerstand\\\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/\",\"name\":\"Florian Horsefood\",\"description\":\"Back to Basic &amp; Health Protection!\",\"publisher\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#organization\",\"name\":\"Florian Pferdefutter\",\"url\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Florian_Horsefood_liggend_RGB.png\",\"contentUrl\":\"https:\\\/\\\/florianhorsefood.nl\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Florian_Horsefood_liggend_RGB.png\",\"width\":1044,\"height\":393,\"caption\":\"Florian Pferdefutter\"},\"image\":{\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/florian-horsefood\\\/about\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/florianhorsefood.nl\\\/de\\\/#\\\/schema\\\/person\\\/ba5046cbcfb040cadeba68e42e52a0f5\",\"name\":\"Pieter de Gouw\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood","description":"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\/Fibre Protein) und Care Fit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/","og_locale":"de_DE","og_type":"article","og_title":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood","og_description":"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\/Fibre Protein) und Care Fit.","og_url":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/","og_site_name":"Florian Horsefood","article_published_time":"2026-02-24T08:47:39+00:00","article_modified_time":"2026-02-26T11:32:29+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp","type":"image\/jpeg"}],"author":"Pieter de Gouw","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Pieter de Gouw"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#article","isPartOf":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/"},"author":{"name":"Pieter de Gouw","@id":"https:\/\/florianhorsefood.nl\/de\/#\/schema\/person\/ba5046cbcfb040cadeba68e42e52a0f5"},"headline":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten","datePublished":"2026-02-24T08:47:39+00:00","dateModified":"2026-02-26T11:32:29+00:00","mainEntityOfPage":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/"},"wordCount":15,"publisher":{"@id":"https:\/\/florianhorsefood.nl\/de\/#organization"},"image":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp","keywords":["Darmflora","Darmgesundheit","Pferd mit vermindertem Appetit","reduzierte Leistung des Pferdes","Schlankes Pferd","Widerstand","Widerstandspferd"],"articleSection":["Widerstand"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/","url":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/","name":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten - Florian Horsefood","isPartOf":{"@id":"https:\/\/florianhorsefood.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#primaryimage"},"image":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp","datePublished":"2026-02-24T08:47:39+00:00","dateModified":"2026-02-26T11:32:29+00:00","description":"Entdecken Sie, wie Darmgesundheit und Widerstandskraft bei Pferden zusammenh\u00e4ngen. Anschaulich erkl\u00e4rt, mit praktischen Tipps und Ratschl\u00e4gen zu Florians Raufuttermischungen (Fibre Grass, Basic Growth\/Fibre Protein) und Care Fit.","breadcrumb":{"@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#primaryimage","url":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp","contentUrl":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2026\/02\/gezonde-darmen-paard.webp","width":1080,"height":1080,"caption":"Gesunder Darm und starke Abwehrkr\u00e4fte mit Florian Horsefood."},{"@type":"BreadcrumbList","@id":"https:\/\/florianhorsefood.nl\/de\/widerstand\/gesunder-darm-starke-abwehrkraefte-warum-verdauung-und-immunsystem-bei-ihrem-pferd-so-eng-zusammenarbeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/florianhorsefood.nl\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Gesunder Darm, starke Abwehrkr\u00e4fte: Warum Verdauung und Immunsystem bei Ihrem Pferd so eng zusammenarbeiten"}]},{"@type":"WebSite","@id":"https:\/\/florianhorsefood.nl\/de\/#website","url":"https:\/\/florianhorsefood.nl\/de\/","name":"Florian Horsefood","description":"Back to Basic &amp; Health Protection!","publisher":{"@id":"https:\/\/florianhorsefood.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/florianhorsefood.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/florianhorsefood.nl\/de\/#organization","name":"Florian Pferdefutter","url":"https:\/\/florianhorsefood.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/florianhorsefood.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2020\/02\/Florian_Horsefood_liggend_RGB.png","contentUrl":"https:\/\/florianhorsefood.nl\/wp-content\/uploads\/2020\/02\/Florian_Horsefood_liggend_RGB.png","width":1044,"height":393,"caption":"Florian Pferdefutter"},"image":{"@id":"https:\/\/florianhorsefood.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/florian-horsefood\/about\/"]},{"@type":"Person","@id":"https:\/\/florianhorsefood.nl\/de\/#\/schema\/person\/ba5046cbcfb040cadeba68e42e52a0f5","name":"Pieter de Gouw"}]}},"_links":{"self":[{"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/posts\/21880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/comments?post=21880"}],"version-history":[{"count":2,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/posts\/21880\/revisions"}],"predecessor-version":[{"id":21888,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/posts\/21880\/revisions\/21888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/media\/21886"}],"wp:attachment":[{"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/media?parent=21880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/categories?post=21880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/florianhorsefood.nl\/de\/wp-json\/wp\/v2\/tags?post=21880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}